{"id":27927,"date":"2026-06-26T02:46:28","date_gmt":"2026-06-26T05:46:28","guid":{"rendered":"https:\/\/homu.com.ar\/new\/?page_id=27927"},"modified":"2026-06-26T02:48:28","modified_gmt":"2026-06-26T05:48:28","slug":"yaris-cross-xli-70-30","status":"publish","type":"page","link":"https:\/\/homu.com.ar\/new\/yaris-cross-xli-70-30\/","title":{"rendered":"Yaris Cross XLI 70 30"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"27927\" class=\"elementor elementor-27927\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86e6ab4 e-con-full e-flex e-con e-parent\" data-id=\"86e6ab4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-94bbed7 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"94bbed7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"600\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2026\/06\/BannerPlanAhorroYarisCrossFlex-scaled.jpg\" class=\"attachment-full size-full wp-image-27930\" alt=\"\" srcset=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2026\/06\/BannerPlanAhorroYarisCrossFlex-scaled.jpg 2560w, https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2026\/06\/BannerPlanAhorroYarisCrossFlex-300x70.jpg 300w, https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2026\/06\/BannerPlanAhorroYarisCrossFlex-1024x240.jpg 1024w, https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2026\/06\/BannerPlanAhorroYarisCrossFlex-768x180.jpg 768w, https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2026\/06\/BannerPlanAhorroYarisCrossFlex-1536x360.jpg 1536w, https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2026\/06\/BannerPlanAhorroYarisCrossFlex-2048x480.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbfbee9 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"fbfbee9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"861\" height=\"625\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2026\/06\/BannerPlanAhorroYarisCrossFlexM.jpg\" class=\"attachment-full size-full wp-image-27932\" alt=\"\" srcset=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2026\/06\/BannerPlanAhorroYarisCrossFlexM.jpg 861w, https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2026\/06\/BannerPlanAhorroYarisCrossFlexM-300x218.jpg 300w, https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2026\/06\/BannerPlanAhorroYarisCrossFlexM-768x557.jpg 768w\" sizes=\"(max-width: 861px) 100vw, 861px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa1d2e0 e-flex e-con-boxed e-con e-parent\" data-id=\"aa1d2e0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f0b628a elementor-widget elementor-widget-heading\" data-id=\"f0b628a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Yaris Cross XLI CVT Plan 70\/30<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b06347 elementor-widget elementor-widget-heading\" data-id=\"1b06347\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 es un plan 70\/30?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8eb9fdc elementor-widget elementor-widget-text-editor\" data-id=\"8eb9fdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"title-text-contact-btn-image__title-wrapper\"><p class=\"text\">Te permite ahorrar el 70% del valor del veh\u00edculo y el 30% restante lo abon\u00e1s al momento de la adjudicaci\u00f3n. Planific\u00e1 tu econom\u00eda en 84 cuotas.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36b1d78 e-flex e-con-boxed e-con e-parent\" data-id=\"36b1d78\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6635ed2 e-con-full e-flex e-con e-child\" data-id=\"6635ed2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-73b82db e-flex e-con-boxed e-con e-child\" data-id=\"73b82db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49a1138 elementor-widget elementor-widget-heading\" data-id=\"49a1138\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Si necesit\u00e1s m\u00e1s informaci\u00f3n para acceder a tu Plan\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-11e5c23 e-flex e-con-boxed e-con e-child\" data-id=\"11e5c23\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0f6754a elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"0f6754a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/homu.com.ar\/new\/contacto\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CONTACTANOS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2ac0822 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-child\" data-id=\"2ac0822\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-628c7d0 elementor-widget elementor-widget-heading\" data-id=\"628c7d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Suscribite Online\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-943a62e e-flex e-con-boxed e-con e-child\" data-id=\"943a62e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f45ac78 e-flex e-con-boxed e-con e-child\" data-id=\"f45ac78\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c886455 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"c886455\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/suscripcion.toyotaplan.com.ar\/?external=4ddf5af1e4b61c217701f4e0d17492fa7bc9aad463505cef5e9e5353a9cd2b31\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PLAN COROLLA CROSS H\u00cdBRIDO 100%<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5861335 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-child\" data-id=\"5861335\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c26c289 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"c26c289\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/suscripcion.toyotaplan.com.ar\/?external=f27c46b2701d19877594cf4b78848c5e4b279faf9848ad57f89eda6dc77778fb\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PLAN COROLLA CROSS 100%<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-91d8782 e-con-full e-flex e-con e-child\" data-id=\"91d8782\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-44ed316 e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"44ed316\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-22f5b6d e-con-full e-flex e-con e-child\" data-id=\"22f5b6d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3dcf3c3 elementor-widget elementor-widget-ucaddon_card_carousel\" data-id=\"3dcf3c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_card_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Card Carousel -->\n\t\t<link id='font-awesome-css' href='https:\/\/homu.com.ar\/new\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/homu.com.ar\/new\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='owl-carousel-css' href='https:\/\/homu.com.ar\/new\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/owl-carousel-new\/assets\/owl.carousel.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Card Carousel *\/\n\n#uc_card_carousel_elementor_3dcf3c3-wrapper\n{\n  min-height:1px;\n}\n#uc_card_carousel_elementor_3dcf3c3 *{\n\t-webkit-box-sizing: border-box;\n\t-moz-box-sizing: border-box;\n\tbox-sizing: border-box;\n}\n\n#uc_card_carousel_elementor_3dcf3c3 .ue-carousel-item\n{\n  overflow:hidden;\n  transition:0.3s;\n}\n\n#uc_card_carousel_elementor_3dcf3c3 .uc_classic_carousel_container_holder\n{\n\tdisplay:block;\n\tposition:relative;\n\twidth:100%;\n    box-sizing: border-box;\n}\n.card_carousel_title\n{\n\tfont-size:21px;\n}\n\n.uc_classic_carousel .uc_classic_carousel_border\n{\n\tdisplay:block;\n    margin:0 auto;\n}\n\n.uc_classic_carousel  .uc_classic_carousel_placeholder img\n{\n\twidth:100%;\n    \n    display:inline-flex;\n}\n.uc_classic_carousel .uc_classic_carousel_content\n{\n  display: flex;\n flex-flow: column nowrap;\n}\n\n.uc_classic_carousel .ue_button\n{\n  margin-top:auto;\n\n}\n\n.uc_classic_carousel .uc_classic_carousel_content .uc_more_btn {\n\tdisplay:inline-block;\n\ttext-decoration:none;\n\ttransition: all 0.5s ease;\n}\n\n\n#uc_card_carousel_elementor_3dcf3c3 .owl-dots {\noverflow:hidden;\ntext-align:center;\n}\n\n#uc_card_carousel_elementor_3dcf3c3 .owl-dot {\nborder-radius:50%;\ndisplay:inline-block;\n}\n\n#uc_card_carousel_elementor_3dcf3c3 .owl-nav .owl-prev{\n    position:absolute;\n    display:inline-block;\n    text-align:center;\n}\n#uc_card_carousel_elementor_3dcf3c3 .owl-nav .owl-next{\n  position:absolute;\n  display:inline-block;\n  text-align:center;\n}\n\n#uc_card_carousel_elementor_3dcf3c3 .owl-nav .disabled\n{\n    display: none;  \n}\n\n\n#uc_card_carousel_elementor_3dcf3c3 .ue-item-icon\n{\n  line-height:1em;\n  display:inline-flex;\n  justify-content:center;\n  align-items:center;\n  \n}\n\n#uc_card_carousel_elementor_3dcf3c3 .ue-item-icon svg\n{\n  height:1em;\n  width:1em;\n}\n\n#uc_card_carousel_elementor_3dcf3c3 .ue-item-icon-wrapper\n{\n  display:flex;\n}\n\n#uc_card_carousel_elementor_3dcf3c3 .uc_classic_carousel_container_holder {\n\t max-width: ;\n}\n\n\n\n@media screen and (max-width: 1024px) {\n  #uc_card_carousel_elementor_3dcf3c3 .uc_classic_carousel_container_holder {\n\t max-width: ;\n  }\n}\n\n@media screen and (max-width: 767px) {\n  #uc_card_carousel_elementor_3dcf3c3 .uc_classic_carousel_container_holder {\n    max-width: ;\n  }\n}\n\n<\/style>\n\n<div class=\"uc_classic_carousel\" id=\"uc_card_carousel_elementor_3dcf3c3-wrapper\">\n        <div class=\"uc_carousel owl-carousel uc-items-wrapper  \" id=\"uc_card_carousel_elementor_3dcf3c3\"  >\n          \t<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-391cb94\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/wQ8QT4H75l.jpg\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/wQ8QT4H75l.jpg\" alt=\"wQ8QT4H75l\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Llantas de aleaci\u00f3n de 18\u201d<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\">Disponible en versi\u00f3n SEG.<\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-cdeb5f8\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/ashybFAsAx.png\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/ashybFAsAx.png\" alt=\"ashybFAsAx\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Faros delanteros Bi-LED con regulaci\u00f3n en altura<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\">Disponible a partir de versi\u00f3n\/es XEI CVT.<\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-a5bdc49\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/f2fuokL4KC.jpg\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/f2fuokL4KC.jpg\" alt=\"f2fuokL4KC\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Faros traseros de LED con efecto cortina<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\"><\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-c6eab2d\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/jbbfcsnfW5.png\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/jbbfcsnfW5.png\" alt=\"jbbfcsnfW5\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Asientos tapizados en cuero natural y ecol\u00f3gico<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\"><\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-c795bf4\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/cB3nKxVvQP.jpg\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/cB3nKxVvQP.jpg\" alt=\"cB3nKxVvQP\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Techo solar con apertura el\u00e9ctrica<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\">Disponible en versiones XEI y SEG.<\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-382adf9\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/Il6KDneIwr.png\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/Il6KDneIwr.png\" alt=\"Il6KDneIwr\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Climatizador autom\u00e1tico digital Bi-Zona<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\">Disponible a partir de versi\u00f3n\/es XEI CVT.<\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-0750150\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/462vfR6HCN.png\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/462vfR6HCN.png\" alt=\"462vfR6HCN\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Display de informaci\u00f3n m\u00faltiple con pantalla color de 7\u201d.<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\">Disponible en versiones SEG y SEG HEV.<\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-ade8906\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/ygS8i1bRUP.jpg\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/ygS8i1bRUP.jpg\" alt=\"ygS8i1bRUP\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Pantalla t\u00e1ctil de 8\" con Apple CarPlay\u00ae y Android Auto\u00ae**<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\">Disponible en versiones SEG y SEG HEV.<\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-7995b85\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/DEtzWEVOqb.jpg\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/DEtzWEVOqb.jpg\" alt=\"DEtzWEVOqb\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Monitor de c\u00e1mara de estacionamiento<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\"><\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-b6a98d2\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/gDXmcUfVhV.jpg\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/gDXmcUfVhV.jpg\" alt=\"gDXmcUfVhV\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Cargador inal\u00e1mbrico para smartphones**.<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\">Disponible en versiones SEG y SEG HEV.<\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-0a1d24e\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/vT8SP7eaui.png\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/vT8SP7eaui.png\" alt=\"vT8SP7eaui\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Control de Velocidad Crucero Adaptativo (ACC)*.<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\">Disponible en versiones SEG y SEG HEV.<\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-97039b8\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/6uNHGRWpXp.png\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/6uNHGRWpXp.png\" alt=\"6uNHGRWpXp\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Sistema de alerta de cambio de carril (LDA)*.<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\">Disponible en versiones SEG y SEG HEV.<\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-af2837c\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/yfWGQqdXV5.png\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/yfWGQqdXV5.png\" alt=\"yfWGQqdXV5\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Sistema de pre colisi\u00f3n frontal (PCS)*.<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\">Disponible en versiones SEG y SEG HEV.<\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-297f4c7\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/0s9pxJecsa.png\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/0s9pxJecsa.png\" alt=\"0s9pxJecsa\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Sistema Luces Altas Autom\u00e1ticas (AHB)*<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\">Disponible en versiones SEG y SEG HEV.<\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-601a688\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/4NM1gjBJFL.jpg\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/4NM1gjBJFL.jpg\" alt=\"4NM1gjBJFL\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Control de estabilidad (VSC)<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\"><\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-3c88b79\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/F46ZobsfFT.jpg\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/F46ZobsfFT.jpg\" alt=\"F46ZobsfFT\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Asistente de arranque en pendientes (HAC)<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\"><\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-f556cd2\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/lmvYkFHrzc.jpg\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/lmvYkFHrzc.jpg\" alt=\"lmvYkFHrzc\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Sensores de estacionamiento delanteros y traseros<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\"><\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-c6e7429\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/q1d1mmnQpl.jpg\"  src=\"https:\/\/homu.com.ar\/new\/wp-content\/uploads\/2023\/09\/q1d1mmnQpl.jpg\" alt=\"q1d1mmnQpl\" width=\"270\" height=\"150\">\n      <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n          \t\n      <div  class=\"card_carousel_title\">Tuercas de seguridad para llantas<\/div>\n          \t\n    \n      \n    <p class=\"card_carousel_text\"><\/p>    \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n\n      <\/div>\n<\/div>\n<!-- end Card Carousel -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Yaris Cross XLI CVT Plan 70\/30 \u00bfQu\u00e9 es un plan 70\/30? Te permite ahorrar el 70% del valor del veh\u00edculo y el 30% restante lo abon\u00e1s al momento de la adjudicaci\u00f3n. Planific\u00e1 tu econom\u00eda en 84 cuotas. Si necesit\u00e1s m\u00e1s informaci\u00f3n para acceder a tu Plan CONTACTANOS Suscribite Online PLAN COROLLA CROSS H\u00cdBRIDO 100% PLAN [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-27927","page","type-page","status-publish","hentry"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/homu.com.ar\/new\/wp-json\/wp\/v2\/pages\/27927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/homu.com.ar\/new\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/homu.com.ar\/new\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/homu.com.ar\/new\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/homu.com.ar\/new\/wp-json\/wp\/v2\/comments?post=27927"}],"version-history":[{"count":4,"href":"https:\/\/homu.com.ar\/new\/wp-json\/wp\/v2\/pages\/27927\/revisions"}],"predecessor-version":[{"id":27935,"href":"https:\/\/homu.com.ar\/new\/wp-json\/wp\/v2\/pages\/27927\/revisions\/27935"}],"wp:attachment":[{"href":"https:\/\/homu.com.ar\/new\/wp-json\/wp\/v2\/media?parent=27927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}